{"id":593,"date":"2023-07-03T19:04:55","date_gmt":"2023-07-03T19:04:55","guid":{"rendered":"https:\/\/amasyria.com\/?page_id=593"},"modified":"2025-08-24T08:37:25","modified_gmt":"2025-08-24T08:37:25","slug":"projects","status":"publish","type":"page","link":"https:\/\/www.amasyria.com\/en\/repository\/projects\/","title":{"rendered":"projects"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"593\" class=\"elementor elementor-593\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b753d6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b753d6\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e066a0b\" data-id=\"e066a0b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8a9203 elementor-widget elementor-widget-heading\" data-id=\"d8a9203\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-xl\">projects<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cdf8cd elementor-widget elementor-widget-htmega-search-addons\" data-id=\"5cdf8cd\" data-element_type=\"widget\" data-widget_type=\"htmega-search-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t            <div class=\"htmega-search-box htmega-search-style-1 sid5cdf8cd\" >\n                <form action=\"https:\/\/www.amasyria.com\/en\/\" method=\"get\" role=\"search\">\n\n                    <input placeholder=\"Search\" type=\"text\" name=\"s\" title=\"Search\" value=\"\" ><button type=\"submit\" class=\"htb-btn btn-search\"><i aria-hidden=\"true\" class=\"fas fa-search\"><\/i> <\/button>\n                <\/form>\n            <\/div>\n                                \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9299fb elementor-widget__width-inherit elementor-widget elementor-widget-ucaddon_post_blocks\" data-id=\"b9299fb\" data-element_type=\"widget\" data-widget_type=\"ucaddon_post_blocks.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Post Blocks -->\n\t\t<link id='font-awesome-css' href='https:\/\/www.amasyria.com\/wp-content\/plugins\/unlimited-elements-for-elementor\/assets_libraries\/font-awesome5\/css\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/www.amasyria.com\/wp-content\/plugins\/unlimited-elements-for-elementor\/assets_libraries\/font-awesome5\/css\/fontawesome-v4-shims.css' type='text\/css' rel='stylesheet' >\n\n\t\t\t<style type=\"text\/css\">\/* widget: Post Blocks *\/\n\n\n\n#uc_post_blocks_elementor_b9299fb {\n    display:grid;\n}\n#uc_post_blocks_elementor_b9299fb .ue_post_blocks_box\n{\n  overflow:hidden;\n}\n\n#uc_post_blocks_elementor_b9299fb .ue_post_blocks_image\n{\n  overflow:hidden;\n}\n#uc_post_blocks_elementor_b9299fb .ue_post_blocks_image img\n{\n  width:100%;\n  display:block;\n}\n#uc_post_blocks_elementor_b9299fb .ue_post_blocks_link a\n{\n  display:inline-block;\n  text-decoration:none;\n  text-align:center;\n}\n\n\n#uc_post_blocks_elementor_b9299fb .ue-grid-item-meta-data\n{\n  display:inlin-flex;\n  flex-wrap: wrap;\n}\n\n.ue-grid-item-meta-data\n{\n  font-size:12px;\n}\n\n#uc_post_blocks_elementor_b9299fb .ue-grid-item-meta-data-icon\n{\n  line-height:1em;\n}\n\n#uc_post_blocks_elementor_b9299fb .ue-grid-item-meta-data-icon svg\n{\n  width:1em;\n  height:1em;\n}\n\n#uc_post_blocks_elementor_b9299fb .ue_post_blocks_box{\n  display: flex;\n  flex-direction: column;\n}\n#uc_post_blocks_elementor_b9299fb .ue_post_blocks_content{\n display: flex; flex-grow: 1;\n flex-direction: column;\n}\n#uc_post_blocks_elementor_b9299fb .ue_post_blocks_link{ margin-top: auto;\n}\n\n.ue-grid-item-category a\n{\n  display:inline-block;\n  font-size:10px;\n  text-transform:uppercase;\n}\n\n<\/style>\n\n\t\t\t<div id=\"uc_post_blocks_elementor_b9299fb\" class=\"ue_post_blocks uc-items-wrapper uc-filterable-grid\"  data-ajax='true'  data-filterbehave='ajax'  querydata='{&quot;count_posts&quot;:20,&quot;total_posts&quot;:24,&quot;page&quot;:1,&quot;num_pages&quot;:2,&quot;orderby&quot;:&quot;title&quot;,&quot;orderdir&quot;:&quot;asc&quot;}'>\n    <div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/al-kawthar-mosque\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/04\/\u00a9-AMASyria-2023sy_di__0005ph01dig-scaled.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/04\/\u00a9-AMASyria-2023sy_di__0005ph01dig-scaled.jpg\" alt=\"Al-Kawthar mosque_Abdul Mohsen Kodmani_southern elevation of the\" width=\"2560\" height=\"1441\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/al-kawthar-mosque\/\">Al-Kawthar Mosque<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/central-library-of-damascus-university\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/04\/AMASyria_REF_M02N005_051962Pg9Fig1.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/04\/AMASyria_REF_M02N005_051962Pg9Fig1.jpg\" alt=\"Central Library of Damascus University_Khalil-AlFarra_the librar\" width=\"1689\" height=\"1080\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/central-library-of-damascus-university\/\">Central Library of Damascus University<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/commercial-and-governmental-complex-of-deir-ezzour\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/04\/sy_dy_0004ph05dig-scaled.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/04\/sy_dy_0004ph05dig-scaled.jpg\" alt=\"Commercial and governmental complex of Deir Ezzour_Bashir Muhand\" width=\"2560\" height=\"1628\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/commercial-and-governmental-complex-of-deir-ezzour\/\">Commercial and governmental complex of Deir Ezzour<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/damascus-car-and-bus-station-1st-prize\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/AMASyria_REF_m02n021_091967PG77fig1.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/AMASyria_REF_m02n021_091967PG77fig1.jpg\" alt=\"Damascus Cars and Buses station competition_Nizar Al-Farra_gener\" width=\"2547\" height=\"1140\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/damascus-car-and-bus-station-1st-prize\/\">Damascus car and bus station - 1st prize<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/damascus-car-and-bus-station-2nd-prize\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/04\/AMASyria_REF_m02n021_091967_PG73_fig1.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/04\/AMASyria_REF_m02n021_091967_PG73_fig1.jpg\" alt=\"Damascus Car and Bus Station_Abd Al-Rauf Al-Kasm_general perspec\" width=\"1756\" height=\"1080\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/damascus-car-and-bus-station-2nd-prize\/\">Damascus Car and Bus Station - 2nd prize<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/damascus-car-and-bus-station-3rd-prize\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/AMASyria_REF_m02n021_091967PG71fig1-scaled.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/AMASyria_REF_m02n021_091967PG71fig1-scaled.jpg\" alt=\"Damascus Car and Bus Station_Sabri AlMalki_General perspective_m\" width=\"2560\" height=\"999\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/damascus-car-and-bus-station-3rd-prize\/\">Damascus Car and Bus Station - 3rd prize<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/damascus-car-and-bus-station-4th-prize\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/AMASyria_REF_m02n021_091967PG67fig1.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/AMASyria_REF_m02n021_091967PG67fig1.jpg\" alt=\"Damascus Cars and Buses station competition_Paul Chiniara_genera\" width=\"1815\" height=\"1140\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/damascus-car-and-bus-station-4th-prize\/\">Damascus Car and Bus Station - 4th prize<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/daraa-city-hall\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/04\/AMASyria_REF_m02n020_051967Pg33fig1.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/04\/AMASyria_REF_m02n020_051967Pg33fig1.jpg\" alt=\"Daraa city hall_Abd al-Rauf al-Kasm_Youssef Abu Hadid_General pe\" width=\"1952\" height=\"1080\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/daraa-city-hall\/\">Daraa City Hall<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/engineers-retirement-trust-building\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/sy_la_0016ph01dig.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/sy_la_0016ph01dig.jpg\" alt=\"The Engineer&#039;s Retirement Trust building_Hisham Nabsh and Ahmad\" width=\"640\" height=\"480\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/engineers-retirement-trust-building\/\">Engineers\u2019 Retirement Trust building<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/engineers-retirement-trust-building-2nd-prize\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/AMASyria_REF_m02n031_071970PG78fig3.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/AMASyria_REF_m02n031_071970PG78fig3.jpg\" alt=\"The Engineer&#039;s Retirement Trust building_Mustafa AlSheikh _gener\" width=\"1584\" height=\"1140\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/engineers-retirement-trust-building-2nd-prize\/\">Engineers\u2019 Retirement Trust building - 2nd prize<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/engineers-retirement-trust-building-3rd-prize\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/AMASyria_REF_m02n031_071970PG80fig1.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/AMASyria_REF_m02n031_071970PG80fig1.jpg\" alt=\"&quot;The Engineer&#039;s Retirement Trust building_Marwan Haddad _genera\" width=\"1595\" height=\"1140\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/engineers-retirement-trust-building-3rd-prize\/\">Engineers\u2019 Retirement Trust building - 3rd prize<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/faculty-of-law-at-the-university-of-aleppo\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/AMASyria_REF_m02n009_101963PG34Fig1.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/AMASyria_REF_m02n009_101963PG34Fig1.jpg\" alt=\"Faculty of Law_University of Aleppo_Mhd Samir Al-Moudarres _Main\" width=\"1952\" height=\"1080\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/faculty-of-law-at-the-university-of-aleppo\/\">Faculty of Law at the University of Aleppo<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/faculty-of-medicine-at-the-university-of-aleppo\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/sy_hl_0002ph04dig.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/sy_hl_0002ph04dig.jpg\" alt=\"Faculty of Medicine at the University of Aleppo_Ahmed Adnan Ikhl\" width=\"1381\" height=\"1008\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/faculty-of-medicine-at-the-university-of-aleppo\/\">Faculty of Medicine at the University of Aleppo<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/latakia-university-design-proposal-george-candilis\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2026\/01\/AMASyria_ref_C2_044_071973_016fig01.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2026\/01\/AMASyria_ref_C2_044_071973_016fig01.jpg\" alt=\"AMASyria_ref_C2_044_071973_016fig01\" width=\"1242\" height=\"1015\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/latakia-university-design-proposal-george-candilis\/\">Latakia University design proposal - George Candilis<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/latakia-university-design-proposal-hans-zwimpfer\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2026\/01\/AMASyria_ref_C2_044_071973_043fig08.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2026\/01\/AMASyria_ref_C2_044_071973_043fig08.jpg\" alt=\"AMASyria_ref_C2_044_071973_043fig08\" width=\"1242\" height=\"1004\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/latakia-university-design-proposal-hans-zwimpfer\/\">Latakia University design proposal - Hans Zwimpfer<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/latakia-university-design-proposal-jean-dubuisson\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2026\/01\/AMASyria_ref_C2_044_071973_019fig02.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2026\/01\/AMASyria_ref_C2_044_071973_019fig02.jpg\" alt=\"AMASyria_ref_C2_044_071973_019fig02\" width=\"1242\" height=\"1061\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/latakia-university-design-proposal-jean-dubuisson\/\">Latakia University design proposal - Jean Dubuisson<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/latakia-university-design-proposal-massimo-ciamarra\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2026\/01\/AMASyria_ref_C2_044_071973_027fig01.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2026\/01\/AMASyria_ref_C2_044_071973_027fig01.jpg\" alt=\"AMASyria_ref_C2_044_071973_027fig01\" width=\"1242\" height=\"1004\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/latakia-university-design-proposal-massimo-ciamarra\/\">Latakia University design proposal - Massimo Ciamarra<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/latakia-university-design-proposal-rambald-von-steinbuchel\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2026\/01\/AMASyria_ref_C2_044_071973_029fig01.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2026\/01\/AMASyria_ref_C2_044_071973_029fig01.jpg\" alt=\"AMASyria_ref_C2_044_071973_029fig01\" width=\"1242\" height=\"1008\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/latakia-university-design-proposal-rambald-von-steinbuchel\/\">Latakia University design proposal - Rambald Von Steinbuchel<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/residential-complex-for-workers-at-damascus-international-airport\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/sy_rd_0007ph17dig.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/sy_rd_0007ph17dig.jpg\" alt=\"Residential complex for workers in Damascus International Airpor\" width=\"795\" height=\"587\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/residential-complex-for-workers-at-damascus-international-airport\/\">Residential Complex for workers at Damascus International Airport\u00a0<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n<div class=\"ue_post_blocks_box\">\n    <div class=\"ue_post_blocks_image\">\n    <a href=\"https:\/\/www.amasyria.com\/en\/syrian-insurance-corporation-building\/\" style=\"display:block;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/sydi__0010ph25dig-scaled.jpg\"  src=\"https:\/\/www.amasyria.com\/wp-content\/uploads\/2024\/05\/sydi__0010ph25dig-scaled.jpg\" alt=\"Syrian Insurance Corporation building_Youssef Abu Hadid_photo of\" width=\"2560\" height=\"2229\"><\/a>\n  <\/div>\n    <div class=\"ue_post_blocks_content\">\n      \n     \n         \n    <div class=\"ue_post_blocks_title\"><a href=\"https:\/\/www.amasyria.com\/en\/syrian-insurance-corporation-building\/\">Syrian Insurance Corporation building<\/a><\/div>    \n        \n    \n          <\/div>\n<\/div>\n\n<\/div>\n\t\t\t<!-- end Post Blocks -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31be9e7 elementor-widget elementor-widget-ucaddon_archive_pagination\" data-id=\"31be9e7\" data-element_type=\"widget\" data-widget_type=\"ucaddon_archive_pagination.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Post Pagination -->\n\n\t\t\t<style type=\"text\/css\">\/* widget: Post Pagination *\/\n\n#uc_archive_pagination_elementor_31be9e7 nav\n{\n  padding:0px;\n  margin:0px;\n}\n\n#uc_archive_pagination_elementor_31be9e7 \n{\n  display:flex;\n  flex-wrap: wrap;\n  justify-content:center;\n}\n\n#uc_archive_pagination_elementor_31be9e7 .nav-links\n{\n  display:flex;\n  justify-content:center;\n}\n\n#uc_archive_pagination_elementor_31be9e7 .nav-links > *\n{\n}\n\n#uc_archive_pagination_elementor_31be9e7 .page-numbers\n{\n  display:flex;\n  \n  align-items:center;\n  justify-content:center;\n  transition:0.3s;\n  line-height:1em;\n}\n\n\n#uc_archive_pagination_elementor_31be9e7 a.page-numbers, #uc_archive_pagination_elementor_31be9e7 .dots\n{\n  color:#000;\n  background-color:;\n}\n\n#uc_archive_pagination_elementor_31be9e7 a.page-numbers:hover\n{\n  color:#6e6e6e;\n  background-color:#eeeeee;\n}\n\n#uc_archive_pagination_elementor_31be9e7 .page-numbers.current,\n#uc_archive_pagination_elementor_31be9e7 .page-numbers.current:hover\n{\n  background-color:#3FA688;\n  color:#ffffff;\n}\n\n\n#uc_archive_pagination_elementor_31be9e7 .page-numbers.prev, #uc_archive_pagination_elementor_31be9e7 .page-numbers.next\n{\n  padding-left:15px;\n  padding-right:15px;\n}\n\n\n\n#uc_archive_pagination_elementor_31be9e7 .prev:before {\n   font-family: \"Font Awesome 5 Free\";\n   content: \"\\f053\";\n   display: inline-block;\n   vertical-align: middle;\n   font-weight: 900;\n   padding-right:10px;}\n\n#uc_archive_pagination_elementor_31be9e7 .next:after {\n   font-family: \"Font Awesome 5 Free\";\n   content: \"\\f054\";\n   display: inline-block;\n   vertical-align: middle;\n   font-weight: 900;\n   padding-left:10px;}\n\n#uc_archive_pagination_elementor_31be9e7.uc-ajax-loading{\n\topacity:1 !important;\n}\n\n#uc_archive_pagination_elementor_31be9e7.uc-ajax-loading .current{\n\tposition:relative;\n    overflow:hidden;\n}\n\n\n#uc_archive_pagination_elementor_31be9e7.uc-ajax-loading .current:before{\n  content: \"\";\n  display:block;\n  width:100%;\n  height:100%;\n  box-sizing:border-box;\n  position:absolute;\n  top:0px;\n  left:0px;\n  background-color: #c2c2c2;\n  animation: uc-spinning-border 0.5s linear infinite;\n  opacity:50%;\n  border-radius:inherit;\n}\n\n@keyframes uc-spinning-border {\n\t0%{transform: scale(0);}\n\t100%{transform: scale(1); }\t\n}\n\n\n\n<\/style>\n\n\t\t\t<div id=\"uc_archive_pagination_elementor_31be9e7\" class=\"archive_pagination uc-filter-pagination\">\n<span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.amasyria.com\/en\/repository\/projects\/2\/\">2<\/a>\n<\/div>\n\t\t\t<!-- end Post Pagination -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9e9c46d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e9c46d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f44f0c9\" data-id=\"f44f0c9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcf5ef2 elementor-widget elementor-widget-text-editor\" data-id=\"fcf5ef2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>We are constantly working on collecting and archiving data related to the subject of the initiative |architectural documents and drawings, old and new photos, architectural competitions, sketches, project description, in addition to oral history and narratives| and we appreciate any contribution in this regard.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-463c6e9\" data-id=\"463c6e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f0d396 elementor-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"0f0d396\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.amasyria.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Contribute<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>projects Al-Kawthar Mosque Central Library of Damascus University Commercial and governmental complex of Deir Ezzour Damascus car and bus station &#8211; 1st prize Damascus Car and Bus Station &#8211; 2nd prize Damascus Car and Bus Station &#8211; 3rd prize Damascus Car and Bus Station &#8211; 4th prize Daraa City Hall Engineers\u2019 Retirement Trust building Engineers\u2019 &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.amasyria.com\/en\/repository\/projects\/\"> <span class=\"screen-reader-text\">projects<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":8934,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","cybocfi_hide_featured_image":"","_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"class_list":["post-593","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.amasyria.com\/en\/wp-json\/wp\/v2\/pages\/593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amasyria.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.amasyria.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.amasyria.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amasyria.com\/en\/wp-json\/wp\/v2\/comments?post=593"}],"version-history":[{"count":206,"href":"https:\/\/www.amasyria.com\/en\/wp-json\/wp\/v2\/pages\/593\/revisions"}],"predecessor-version":[{"id":7014,"href":"https:\/\/www.amasyria.com\/en\/wp-json\/wp\/v2\/pages\/593\/revisions\/7014"}],"up":[{"embeddable":true,"href":"https:\/\/www.amasyria.com\/en\/wp-json\/wp\/v2\/pages\/8934"}],"wp:attachment":[{"href":"https:\/\/www.amasyria.com\/en\/wp-json\/wp\/v2\/media?parent=593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}